{"id":136277,"date":"2024-07-24T10:37:04","date_gmt":"2024-07-24T10:37:04","guid":{"rendered":"https:\/\/350.org\/fr\/?p=136277"},"modified":"2024-07-29T09:30:18","modified_gmt":"2024-07-29T09:30:18","slug":"laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes","status":"publish","type":"post","link":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/","title":{"rendered":"L&rsquo;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse"},"content":{"rendered":"<p>Ce blog est \u00e9glament disponible <a href=\"https:\/\/350.org\/global-south-aspiration-for-principled-finances\/\" target=\"_blank\" rel=\"noopener\">en anglais<\/a> et <a href=\"https:\/\/350.org\/id\/aspirasi-global-selatan-untuk-prinsip-keuangan\/\" target=\"_blank\" rel=\"noopener\">en indon\u00e9sien<\/a>.<\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">350.org est fi\u00e8re d&rsquo;avoir accueilli, le 10 juin 2024, une <a href=\"https:\/\/350.org\/press-release\/civil-society-organizations-launch-principles-for-a-fair-jetp-framework-ahead-of-g7-leaders-summit\/\">conf\u00e9rence de presse d\u00e9terminante pour le lancement des \u00ab\u00a0Principes mondiaux pour les partenariats pour une transition \u00e9nerg\u00e9tique juste (JETP)<\/a>\u00ab\u00a0, qui constitue un moment important dans la lutte pour une finance climat \u00e9quitable. Cet \u00e9v\u00e9nement en ligne, traduit en anglais, en fran\u00e7ais, en vietnamien et en bahasa indonesia, a rassembl\u00e9 des repr\u00e9sentants de la soci\u00e9t\u00e9 civile d&rsquo;Afrique du Sud, d&rsquo;Indon\u00e9sie, du S\u00e9n\u00e9gal, du Vietnam et d&rsquo;ailleurs, qui ont insist\u00e9 sur l&rsquo;urgence de la mise en place d&rsquo;une finance fond\u00e9e sur des principes pour la transition \u00e9nerg\u00e9tique dans les pays du Sud.<\/span><\/p>\n<h4><b>Points cl\u00e9s :<\/b><\/h4>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Principes pour des JETP \u00e9quitables<\/b><span style=\"font-weight: 400;\"> : d\u00e9velopp\u00e9s en collaboration avec la soci\u00e9t\u00e9 civile et les collectivit\u00e9s locales des pays b\u00e9n\u00e9ficiaires des JETP (partenariats pour une transition \u00e9nerg\u00e9tique juste), ces principes mettent l&rsquo;accent sur les contextes locaux et l&rsquo;inclusion des populations locales dans les processus de prise de d\u00e9cision. Ils visent \u00e0 valoriser la soci\u00e9t\u00e9 civile, \u00e0 servir de base \u00e0 l&rsquo;action et, finalement, \u00e0 garantir que la transition vers une \u00e9nergie \u00e0 faibles \u00e9missions de carbone soit juste et \u00e9quitable.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Des voix unies en provenance des pays du Sud<\/b><span style=\"font-weight: 400;\"> : un panel de militant\u00b7e\u00b7s, dont des repr\u00e9sentant\u00b7e\u00b7s de Nu Climate Vision (Afrique du Sud), Lumi\u00e8re Synergie D\u00e9veloppement (S\u00e9n\u00e9gal), International Rivers (Vietnam) et Trend Asia (Indon\u00e9sie), ont exprim\u00e9 les aspirations et les demandes collectives de leurs pays respectifs. Leurs puissants t\u00e9moignages ont soulign\u00e9 la n\u00e9cessit\u00e9 de la transparence, de la redevabilit\u00e9 et de l&rsquo;inclusion dans les JETP.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Appel \u00e0 l&rsquo;action adress\u00e9 aux dirigeants du G7<\/b><span style=\"font-weight: 400;\"> : \u00e0 l&rsquo;approche du sommet des dirigeants du G7, la conf\u00e9rence de presse a \u00e9t\u00e9 l&rsquo;occasion de lancer un appel aux \u00e9conomies les plus riches du monde pour qu&rsquo;elles engagent davantage de moyens financiers. Les militant\u00b7e\u00b7s ont appel\u00e9 les pays du G7 \u00e0 honorer leurs promesses en mati\u00e8re de finance climat pour soutenir les pays du Sud dans leur transition vers une \u00e9conomie lib\u00e9r\u00e9e des combustibles fossiles.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Session interactive de questions-r\u00e9ponses<\/b><span style=\"font-weight: 400;\"> : une session de questions-r\u00e9ponses dynamique a \u00e9t\u00e9 organis\u00e9e lors de cet \u00e9v\u00e9nement, au cours de laquelle les journalistes et les participant\u00b7e\u00b7s se sont entretenus avec les intervenant\u00b7e\u00b7s, afin d&rsquo;approfondir les principes et les cons\u00e9quences plus larges concernant la politique mondiale en mati\u00e8re de climat.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Un engagement qui doit se poursuivre<\/b><span style=\"font-weight: 400;\"> : la conf\u00e9rence de presse s&rsquo;est achev\u00e9e sur un engagement \u00e0 entretenir un dialogue et une collaboration continus. Les principes \u00e9nonc\u00e9s ne sont pas fig\u00e9s et ils \u00e9volueront gr\u00e2ce \u00e0 des consultations r\u00e9guli\u00e8res avec les populations locales et les parties prenantes, afin de conserver leur pertinence et leur efficacit\u00e9.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Le lancement des \u00ab\u00a0Principes mondiaux pour les JETP\u00a0\u00bb constitue seulement une premi\u00e8re \u00e9tape. Alors que la COP29 se pr\u00e9pare, il est essentiel que ces principes guident l&rsquo;approche de la communaut\u00e9 internationale en mati\u00e8re de finance climat. Nous appelons les dirigeants du G7 \u00e0 faire preuve d&rsquo;un r\u00e9el leadership en engageant des ressources significatives pour soutenir une transition \u00e9nerg\u00e9tique juste et \u00e9quitable dans les pays du Sud.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Ensemble, nous pouvons faire en sorte que la transition vers les \u00e9nergies renouvelables soit \u00e9quitable, juste et guid\u00e9e par la voix des personnes les plus touch\u00e9es<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"font-weight: 400;\">Pour plus d&rsquo;informations sur les \u00ab\u00a0Principes mondiaux pour les JETP\u00a0\u00bb et pour suivre nos efforts, voir<\/span><a href=\"http:\/\/350.org\/jetp\"> <span style=\"font-weight: 400;\">350.org\/jetp<\/span><\/a><span style=\"font-weight: 400;\">. Les organisations travaillant sur les JETP peuvent \u00e9galement nous contacter via ce site web.<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une conf\u00e9rence de presse d\u00e9terminante pour le lancement des \u00ab\u00a0Principes mondiaux pour les partenariats pour une transition \u00e9nerg\u00e9tique juste (JETP)\u00a0\u00bb, qui constitue un moment important dans la lutte pour une finance climat \u00e9quitable.<\/p>\n","protected":false},"author":10012254,"featured_media":136281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4,112],"tags":[],"class_list":["post-136277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-finance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse - 350 Fran\u00e7ais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse\" \/>\n<meta property=\"og:description\" content=\"Une conf\u00e9rence de presse d\u00e9terminante pour le lancement des &quot;Principes mondiaux pour les partenariats pour une transition \u00e9nerg\u00e9tique juste (JETP)&quot;, qui constitue un moment important dans la lutte pour une finance climat \u00e9quitable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/\" \/>\n<meta property=\"og:site_name\" content=\"350 Fran\u00e7ais\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T10:37:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T09:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/350.org\/fr\/wp-content\/uploads\/sites\/13\/2024\/07\/Screen-Shot-2024-07-26-at-10.19.56.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1116\" \/>\n\t<meta property=\"og:image:height\" content=\"1016\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"christine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"christine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/\"},\"author\":{\"name\":\"christine\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/#\\\/schema\\\/person\\\/2d3c5290b521ac79fb6cac0a2737911e\"},\"headline\":\"L&rsquo;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse\",\"datePublished\":\"2024-07-24T10:37:04+00:00\",\"dateModified\":\"2024-07-29T09:30:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/\"},\"wordCount\":649,\"image\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/350.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2024\\\/07\\\/Screen-Shot-2024-07-26-at-10.19.56.png\",\"articleSection\":[\"Featured\",\"Finance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/\",\"url\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/\",\"name\":\"L'aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse - 350 Fran\u00e7ais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/350.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2024\\\/07\\\/Screen-Shot-2024-07-26-at-10.19.56.png\",\"datePublished\":\"2024-07-24T10:37:04+00:00\",\"dateModified\":\"2024-07-29T09:30:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/#\\\/schema\\\/person\\\/2d3c5290b521ac79fb6cac0a2737911e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/350.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2024\\\/07\\\/Screen-Shot-2024-07-26-at-10.19.56.png\",\"contentUrl\":\"https:\\\/\\\/350.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2024\\\/07\\\/Screen-Shot-2024-07-26-at-10.19.56.png\",\"width\":1116,\"height\":1016},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/350.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/350.org\\\/fr\\\/\",\"name\":\"350 Fran\u00e7ais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/350.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/350.org\\\/fr\\\/#\\\/schema\\\/person\\\/2d3c5290b521ac79fb6cac0a2737911e\",\"name\":\"christine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86c0c1eeed11bb9f4e6751752745f53e3278aadc6b3cadd92a0f02f9571bd986?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86c0c1eeed11bb9f4e6751752745f53e3278aadc6b3cadd92a0f02f9571bd986?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86c0c1eeed11bb9f4e6751752745f53e3278aadc6b3cadd92a0f02f9571bd986?s=96&d=mm&r=g\",\"caption\":\"christine\"},\"url\":\"https:\\\/\\\/350.org\\\/fr\\\/author\\\/christine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse - 350 Fran\u00e7ais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/","og_locale":"fr_FR","og_type":"article","og_title":"L'aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse","og_description":"Une conf\u00e9rence de presse d\u00e9terminante pour le lancement des \"Principes mondiaux pour les partenariats pour une transition \u00e9nerg\u00e9tique juste (JETP)\", qui constitue un moment important dans la lutte pour une finance climat \u00e9quitable.","og_url":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/","og_site_name":"350 Fran\u00e7ais","article_published_time":"2024-07-24T10:37:04+00:00","article_modified_time":"2024-07-29T09:30:18+00:00","og_image":[{"width":1116,"height":1016,"url":"https:\/\/350.org\/fr\/wp-content\/uploads\/sites\/13\/2024\/07\/Screen-Shot-2024-07-26-at-10.19.56.png","type":"image\/png"}],"author":"christine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"christine","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#article","isPartOf":{"@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/"},"author":{"name":"christine","@id":"https:\/\/350.org\/fr\/#\/schema\/person\/2d3c5290b521ac79fb6cac0a2737911e"},"headline":"L&rsquo;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse","datePublished":"2024-07-24T10:37:04+00:00","dateModified":"2024-07-29T09:30:18+00:00","mainEntityOfPage":{"@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/"},"wordCount":649,"image":{"@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#primaryimage"},"thumbnailUrl":"https:\/\/350.org\/fr\/wp-content\/uploads\/sites\/13\/2024\/07\/Screen-Shot-2024-07-26-at-10.19.56.png","articleSection":["Featured","Finance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/","url":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/","name":"L'aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse - 350 Fran\u00e7ais","isPartOf":{"@id":"https:\/\/350.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#primaryimage"},"image":{"@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#primaryimage"},"thumbnailUrl":"https:\/\/350.org\/fr\/wp-content\/uploads\/sites\/13\/2024\/07\/Screen-Shot-2024-07-26-at-10.19.56.png","datePublished":"2024-07-24T10:37:04+00:00","dateModified":"2024-07-29T09:30:18+00:00","author":{"@id":"https:\/\/350.org\/fr\/#\/schema\/person\/2d3c5290b521ac79fb6cac0a2737911e"},"breadcrumb":{"@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#primaryimage","url":"https:\/\/350.org\/fr\/wp-content\/uploads\/sites\/13\/2024\/07\/Screen-Shot-2024-07-26-at-10.19.56.png","contentUrl":"https:\/\/350.org\/fr\/wp-content\/uploads\/sites\/13\/2024\/07\/Screen-Shot-2024-07-26-at-10.19.56.png","width":1116,"height":1016},{"@type":"BreadcrumbList","@id":"https:\/\/350.org\/fr\/laspiration-des-pays-du-sud-a-une-finance-fondee-sur-des-principes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/350.org\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;aspiration des pays du Sud \u00e0 une finance fond\u00e9e sur des principes : retour sur la conf\u00e9rence de presse"}]},{"@type":"WebSite","@id":"https:\/\/350.org\/fr\/#website","url":"https:\/\/350.org\/fr\/","name":"350 Fran\u00e7ais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/350.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/350.org\/fr\/#\/schema\/person\/2d3c5290b521ac79fb6cac0a2737911e","name":"christine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/86c0c1eeed11bb9f4e6751752745f53e3278aadc6b3cadd92a0f02f9571bd986?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/86c0c1eeed11bb9f4e6751752745f53e3278aadc6b3cadd92a0f02f9571bd986?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86c0c1eeed11bb9f4e6751752745f53e3278aadc6b3cadd92a0f02f9571bd986?s=96&d=mm&r=g","caption":"christine"},"url":"https:\/\/350.org\/fr\/author\/christine\/"}]}},"_links":{"self":[{"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/posts\/136277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/users\/10012254"}],"replies":[{"embeddable":true,"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/comments?post=136277"}],"version-history":[{"count":0,"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/posts\/136277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/media\/136281"}],"wp:attachment":[{"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/media?parent=136277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/categories?post=136277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/350.org\/fr\/wp-json\/wp\/v2\/tags?post=136277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}